{"id":329314,"date":"2025-01-04T10:53:47","date_gmt":"2025-01-04T10:53:47","guid":{"rendered":"https:\/\/find.couponsahl.com\/coupons\/serving-tray-from-norseen-3\/"},"modified":"2025-05-23T21:58:21","modified_gmt":"2025-05-23T21:58:21","slug":"serving-tray-from-norseen-3","status":"publish","type":"coupons","link":"https:\/\/find.couponsahl.com\/ar\/coupons\/serving-tray-from-norseen-3\/","title":{"rendered":"\u0635\u064a\u0646\u064a\u0629 \u062a\u0642\u062f\u064a\u0645 \u0645\u0646 \u0646\u0648\u0631\u0633\u064a\u0646"},"content":{"rendered":"<p>\u0635\u064a\u0646\u064a\u0629 \u062a\u0642\u062f\u064a\u0645 \u0627\u0644\u0637\u0639\u0627\u0645 \u0645\u0646 \u0646\u0648\u0631\u0633\u064a\u0646 \u0642\u0637\u0639\u0629 \u0641\u0631\u064a\u062f\u0629 \u062a\u062c\u0645\u0639 \u0628\u064a\u0646 \u0627\u0644\u0623\u0646\u0627\u0642\u0629 \u0648\u0627\u0644\u0639\u0645\u0644\u064a\u0629. \u062a\u0635\u0645\u064a\u0645\u0647\u0627 \u0627\u0644\u0631\u0627\u0642\u064a \u064a\u0645\u0632\u062c \u0628\u064a\u0646 \u0627\u0644\u0641\u062e\u0627\u0645\u0629 \u0648\u0627\u0644\u062a\u0645\u064a\u0632\u060c \u0645\u0636\u064a\u0641\u064b\u0627 \u0644\u0645\u0633\u0629 \u0645\u0646 \u0627\u0644\u0631\u0642\u064a \u0644\u0623\u064a \u0645\u0646\u0627\u0633\u0628\u0629. \u0645\u0635\u0646\u0648\u0639\u0629 \u0645\u0646 \u0645\u0648\u0627\u062f \u0639\u0627\u0644\u064a\u0629 \u0627\u0644\u062c\u0648\u062f\u0629 \u0648\u062a\u062a\u0645\u064a\u0632 \u0628\u062a\u0641\u0627\u0635\u064a\u0644 \u062f\u0642\u064a\u0642\u0629\u060c \u0645\u062b\u0627\u0644\u064a\u0629 \u0644\u062a\u0642\u062f\u064a\u0645 \u0627\u0644\u0637\u0639\u0627\u0645 \u0648\u0627\u0644\u0645\u0634\u0631\u0648\u0628\u0627\u062a \u0628\u0623\u0646\u0627\u0642\u0629. \u0645\u0632\u0648\u062f\u0629 \u0628\u0645\u0642\u0627\u0628\u0636 \u0645\u0631\u064a\u062d\u0629 \u0644\u0633\u0647\u0648\u0644\u0629 \u0627\u0644\u062d\u0645\u0644. \u062a\u0636\u0641\u064a \u0635\u064a\u0646\u064a\u0629 \u062a\u0642\u062f\u064a\u0645 \u0627\u0644\u0637\u0639\u0627\u0645 \u0645\u0646 \u0646\u0648\u0631\u0633\u064a\u0646 \u0644\u0645\u0633\u0629 \u0641\u0627\u062e\u0631\u0629 \u0648\u062c\u0645\u064a\u0644\u0629 \u0639\u0644\u0649 \u0623\u064a \u0641\u0639\u0627\u0644\u064a\u0629.<\/p>","protected":false},"author":1,"featured_media":0,"template":"","offer_categories":[],"locations":[],"stores":[2292],"brands":[],"class_list":["post-329314","coupons","type-coupons","status-publish","hentry","stores-blends"],"cmd_stores":{"id":2292,"name":"\u064a\u0645\u0632\u062c","options":{"popular":"no","store_url":"","store_aff_url":"","store_logo":"","store_banner":"","store_color":"#2780e3","page_title":"","store_category":"","store_display_priority":"0","status":"active"},"cashback_message":"","cashback_message_color":"#4CA14C","cashback_details_page":"https:\/\/find.couponsahl.com\/ar\/coupons\/serving-tray-from-norseen-3\/"},"cmd_locations":[],"cmd_messages":{"deal":"\u062a\u0641\u0639\u064a\u0644 \u0627\u0644\u0635\u0641\u0642\u0629","coupon":"\u0643\u0648\u062f \u0627\u0644\u062a\u0646\u0634\u064a\u0637","copied":"\"[\u0627\u0644\u0643\u0648\u062f]\" \u0645\u0646\u0633\u0648\u062e!","tags":"\u0627\u0644\u0639\u0644\u0627\u0645\u0627\u062a","validity":"\u0635\u0627\u0644\u062d \u062d\u062a\u0649: [EXPIRY]","expired":"\u0645\u0646\u062a\u0647\u064a \u0627\u0644\u0635\u0644\u0627\u062d\u064a\u0629"},"cmd_offer_categories":[],"cmd_meta":{"capi_id":"7065","cmd_type":"deal","cmd_code":"","cmd_url":"","cmd_image_url":"https:\/\/cdn.blendshome.com\/Content\/object\/39bea9ce-551b-4764-9323-d9fedf515ca4.jpeg","cmd_start_date":"2025-01-01","cmd_valid_till":"","cmd_display_priority":"0","cmd_badge":"Best Offer","_edit_last":"1","rank_math_news_sitemap_robots":"index","rank_math_robots":"a:1:{i:0;s:5:\"index\";}"},"_links":{"self":[{"href":"https:\/\/find.couponsahl.com\/ar\/wp-json\/wp\/v2\/coupons\/329314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/find.couponsahl.com\/ar\/wp-json\/wp\/v2\/coupons"}],"about":[{"href":"https:\/\/find.couponsahl.com\/ar\/wp-json\/wp\/v2\/types\/coupons"}],"author":[{"embeddable":true,"href":"https:\/\/find.couponsahl.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/find.couponsahl.com\/ar\/wp-json\/wp\/v2\/media?parent=329314"}],"wp:term":[{"taxonomy":"offer_categories","embeddable":true,"href":"https:\/\/find.couponsahl.com\/ar\/wp-json\/wp\/v2\/offer_categories?post=329314"},{"taxonomy":"locations","embeddable":true,"href":"https:\/\/find.couponsahl.com\/ar\/wp-json\/wp\/v2\/locations?post=329314"},{"taxonomy":"stores","embeddable":true,"href":"https:\/\/find.couponsahl.com\/ar\/wp-json\/wp\/v2\/stores?post=329314"},{"taxonomy":"brands","embeddable":true,"href":"https:\/\/find.couponsahl.com\/ar\/wp-json\/wp\/v2\/brands?post=329314"}],"curies":[{"name":"\u0648\u0648\u0631\u062f\u0628\u0631\u064a\u0633","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}