{"id":586615,"date":"2026-07-01T04:11:40","date_gmt":"2026-07-01T04:11:40","guid":{"rendered":"https:\/\/find.couponsahl.com\/coupons\/code-gives-5-discount-on-all-in-game-items\/"},"modified":"2026-07-01T04:11:40","modified_gmt":"2026-07-01T04:11:40","slug":"code-gives-5-discount-on-all-in-game-items","status":"publish","type":"coupons","link":"https:\/\/find.couponsahl.com\/en\/coupons\/code-gives-5-discount-on-all-in-game-items\/","title":{"rendered":"Code gives 5% discount on all in-game items"},"content":{"rendered":"<p>Maximum basket value 150 EUR<br \/>\nUsage limit per customer\/IP: 5<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","offer_categories":[2160],"locations":[],"stores":[2904],"brands":[],"class_list":["post-586615","coupons","type-coupons","status-publish","hentry","offer_categories-gaming","stores-kinguin-net"],"cmd_stores":{"id":2904,"name":"kinguin.net","options":{"popular":"no","store_url":"https:\/\/www.kinguin.net\/","store_aff_url":"","store_logo":"https:\/\/find.couponsahl.com\/wp-content\/uploads\/2025\/05\/capi_14326bcf68e997e73b514bd47556c5cc.png","store_banner":"","store_color":"#2780e3","page_title":"","store_category":"","store_display_priority":"0","status":"active"},"cashback_message":"","cashback_message_color":"#4CA14C","cashback_details_page":"https:\/\/find.couponsahl.com\/en\/coupons\/code-gives-5-discount-on-all-in-game-items\/"},"cmd_locations":[],"cmd_messages":{"deal":"Activate Deal","coupon":"Activate Code","copied":"\"[code]\" copied!","tags":"Tags","validity":"Valid till: [EXPIRY]","expired":"Expired"},"cmd_offer_categories":[{"id":2160,"name":"Gaming"}],"cmd_meta":{"capi_id":"25445703","cmd_type":"code","cmd_code":"INGAME5","cmd_url":"https:\/\/ficca2021.com\/g\/cgnf55kald65f404fb3073f469699a\/?i=3","cmd_image_url":"http:\/\/cdn.admitad.com\/campaign\/images\/2022\/11\/22\/24298-3ef7b8d5ffac24b0.png","cmd_start_date":"2025-07-03","cmd_valid_till":"","cmd_display_priority":"0","cmd_badge":"5% discount","_edit_lock":"1782879314:1"},"_links":{"self":[{"href":"https:\/\/find.couponsahl.com\/en\/wp-json\/wp\/v2\/coupons\/586615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/find.couponsahl.com\/en\/wp-json\/wp\/v2\/coupons"}],"about":[{"href":"https:\/\/find.couponsahl.com\/en\/wp-json\/wp\/v2\/types\/coupons"}],"wp:attachment":[{"href":"https:\/\/find.couponsahl.com\/en\/wp-json\/wp\/v2\/media?parent=586615"}],"wp:term":[{"taxonomy":"offer_categories","embeddable":true,"href":"https:\/\/find.couponsahl.com\/en\/wp-json\/wp\/v2\/offer_categories?post=586615"},{"taxonomy":"locations","embeddable":true,"href":"https:\/\/find.couponsahl.com\/en\/wp-json\/wp\/v2\/locations?post=586615"},{"taxonomy":"stores","embeddable":true,"href":"https:\/\/find.couponsahl.com\/en\/wp-json\/wp\/v2\/stores?post=586615"},{"taxonomy":"brands","embeddable":true,"href":"https:\/\/find.couponsahl.com\/en\/wp-json\/wp\/v2\/brands?post=586615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}