{"id":2527,"count":9,"description":"","link":"https:\/\/find.couponsahl.com\/en\/store\/anantara-com\/","name":"anantara.com","slug":"anantara-com","taxonomy":"stores","meta":[],"_links":{"self":[{"href":"https:\/\/find.couponsahl.com\/en\/wp-json\/wp\/v2\/stores\/2527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/find.couponsahl.com\/en\/wp-json\/wp\/v2\/stores"}],"about":[{"href":"https:\/\/find.couponsahl.com\/en\/wp-json\/wp\/v2\/taxonomies\/stores"}],"wp:post_type":[{"href":"https:\/\/find.couponsahl.com\/en\/wp-json\/wp\/v2\/coupons?stores=2527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}